{"id":813,"date":"2025-04-16T15:57:32","date_gmt":"2025-04-16T13:57:32","guid":{"rendered":"https:\/\/legnotech.demo3.linoolmostudio.it\/realizzazioni\/terme-sorano-resort\/"},"modified":"2026-06-18T10:28:55","modified_gmt":"2026-06-18T08:28:55","slug":"terme-sorano-resort","status":"publish","type":"realizzazioni","link":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/realizzazioni\/terme-sorano-resort\/","title":{"rendered":"Terme Sorano resort"},"content":{"rendered":"","protected":false},"featured_media":828,"parent":0,"menu_order":38,"template":"","tipologie":[38],"sistemi":[],"class_list":["post-813","realizzazioni","type-realizzazioni","status-publish","has-post-thumbnail","hentry","tipologie-hospitality-strutture-ricettive"],"acf":[],"_links":{"self":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/realizzazioni\/813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/realizzazioni"}],"about":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/types\/realizzazioni"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/media\/828"}],"wp:attachment":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/media?parent=813"}],"wp:term":[{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/tipologie?post=813"},{"taxonomy":"sistemi","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/sistemi?post=813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}