{"id":1012,"date":"2025-04-16T15:32:42","date_gmt":"2025-04-16T13:32:42","guid":{"rendered":"https:\/\/legnotech.demo3.linoolmostudio.it\/realizzazioni\/hotel-nuovo-principe-delle-nevi\/"},"modified":"2025-04-16T15:32:42","modified_gmt":"2025-04-16T13:32:42","slug":"hotel-nuovo-principe-delle-nevi","status":"publish","type":"realizzazioni","link":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/realizzazioni\/hotel-nuovo-principe-delle-nevi\/","title":{"rendered":"Hotel nuovo Principe Delle Nevi"},"content":{"rendered":"<\/p>\n","protected":false},"featured_media":1021,"parent":0,"menu_order":37,"template":"","tipologie":[38],"sistemi":[],"class_list":["post-1012","realizzazioni","type-realizzazioni","status-publish","has-post-thumbnail","hentry","tipologie-hospitality-strutture-ricettive"],"acf":[],"_links":{"self":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/realizzazioni\/1012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/realizzazioni"}],"about":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/types\/realizzazioni"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/media\/1021"}],"wp:attachment":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/media?parent=1012"}],"wp:term":[{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/tipologie?post=1012"},{"taxonomy":"sistemi","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/en\/wp-json\/wp\/v2\/sistemi?post=1012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}