{"id":923,"date":"2025-04-16T15:32:42","date_gmt":"2025-04-16T13:32:42","guid":{"rendered":"https:\/\/legnotech.demo3.linoolmostudio.it\/realizzazioni\/carosello-3000\/"},"modified":"2026-06-18T10:45:48","modified_gmt":"2026-06-18T08:45:48","slug":"carosello-3000","status":"publish","type":"realizzazioni","link":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/realizzazioni\/carosello-3000\/","title":{"rendered":"Carosello 3000"},"content":{"rendered":"","protected":false},"featured_media":938,"parent":0,"menu_order":48,"template":"","tipologie":[60],"sistemi":[46],"class_list":["post-923","realizzazioni","type-realizzazioni","status-publish","has-post-thumbnail","hentry","tipologie-scuole-sport-e-comunita","sistemi-trave-pilastro"],"acf":[],"_links":{"self":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/realizzazioni\/923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/realizzazioni"}],"about":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/types\/realizzazioni"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/media\/938"}],"wp:attachment":[{"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/tipologie?post=923"},{"taxonomy":"sistemi","embeddable":true,"href":"https:\/\/legnotech.demo3.linoolmostudio.it\/de\/wp-json\/wp\/v2\/sistemi?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}